{"id":7439,"date":"2014-08-18T08:19:47","date_gmt":"2014-08-18T08:19:47","guid":{"rendered":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg"},"modified":"2014-08-18T08:19:47","modified_gmt":"2014-08-18T08:19:47","slug":"terra-alta-2","status":"inherit","type":"attachment","link":"https:\/\/www.molloparc.com\/fr\/terra-alta-2\/","title":{"rendered":"terra-alta"},"author":2,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>terra-alta - Moll\u00f3 Parc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"terra-alta - Moll\u00f3 Parc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Moll\u00f3 Parc\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"574\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg\",\"url\":\"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg\",\"name\":\"terra-alta - Moll\u00f3 Parc\",\"isPartOf\":{\"@id\":\"https:\/\/www.molloparc.com\/#website\"},\"datePublished\":\"2014-08-18T08:19:47+00:00\",\"dateModified\":\"2014-08-18T08:19:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.molloparc.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"terra-alta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.molloparc.com\/#website\",\"url\":\"https:\/\/www.molloparc.com\/\",\"name\":\"Moll\u00f3 Parc\",\"description\":\"Parc d&#039;animals dels Prineus a la Vall de Camprodon\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.molloparc.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"terra-alta - Moll\u00f3 Parc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg","og_locale":"fr_FR","og_type":"article","og_title":"terra-alta - Moll\u00f3 Parc","og_url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg","og_site_name":"Moll\u00f3 Parc","og_image":[{"width":574,"height":400,"url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg","url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg","name":"terra-alta - Moll\u00f3 Parc","isPartOf":{"@id":"https:\/\/www.molloparc.com\/#website"},"datePublished":"2014-08-18T08:19:47+00:00","dateModified":"2014-08-18T08:19:47+00:00","breadcrumb":{"@id":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.molloparc.com\/fr\/"},{"@type":"ListItem","position":2,"name":"terra-alta"}]},{"@type":"WebSite","@id":"https:\/\/www.molloparc.com\/#website","url":"https:\/\/www.molloparc.com\/","name":"Moll\u00f3 Parc","description":"Parc d&#039;animals dels Prineus a la Vall de Camprodon","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.molloparc.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg'><img width=\"300\" height=\"209\" src=\"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta-300x209.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta-300x209.jpg 300w, https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg 574w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":574,"height":400,"file":"2014\/08\/terra-alta.jpg","sizes":{"thumbnail":{"file":"terra-alta-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta-150x150.jpg"},"medium":{"file":"terra-alta-300x209.jpg","width":300,"height":209,"mime_type":"image\/jpeg","source_url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta-300x209.jpg"},"image_80_60":{"file":"terra-alta-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta-80x60.jpg"},"image_405_270":{"file":"terra-alta-405x270.jpg","width":405,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta-405x270.jpg"},"image_1140_385":{"file":"terra-alta-574x385.jpg","width":574,"height":385,"mime_type":"image\/jpeg","source_url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta-574x385.jpg"},"image_262_174":{"file":"terra-alta-262x174.jpg","width":262,"height":174,"mime_type":"image\/jpeg","source_url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta-262x174.jpg"},"full":{"file":"terra-alta.jpg","width":574,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"Andrei Botnari","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":null,"source_url":"https:\/\/www.molloparc.com\/wp-content\/uploads\/2014\/08\/terra-alta.jpg","_links":{"self":[{"href":"https:\/\/www.molloparc.com\/fr\/wp-json\/wp\/v2\/media\/7439"}],"collection":[{"href":"https:\/\/www.molloparc.com\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.molloparc.com\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.molloparc.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.molloparc.com\/fr\/wp-json\/wp\/v2\/comments?post=7439"}]}}